{"id":2772,"date":"2016-09-08T19:41:35","date_gmt":"2016-09-08T19:41:35","guid":{"rendered":"http:\/\/www.morganacosplay.com\/?p=2772"},"modified":"2017-08-01T15:05:56","modified_gmt":"2017-08-01T15:05:56","slug":"fran-cosplay","status":"publish","type":"post","link":"http:\/\/www.morganacosplay.com\/es_ES\/portfolio\/fran-cosplay\/","title":{"rendered":"Fran Cosplay"},"content":{"rendered":"<p>Llevo queri\u00e9ndome hacer a Fran desde que s\u00e9 lo que es el cosplay. Fue un flechazo. As\u00ed que despu\u00e9s de tantos a\u00f1os, por fin he podido realizar uno de mis cosplays so\u00f1ados, espero que os guste el resultado!!<\/p>\n<!-- index.php -->\n<div\n\tclass=\"ngg-galleryoverview\"\n\tid=\"ngg-gallery-db74aff99c24009bc42d803e47d53a77-1\">\n\n    \t\t<!-- Thumbnails -->\n\t\t\t\t<div id=\"ngg-image-0\" class=\"ngg-gallery-thumbnail-box\" >\n\t\t\t\t        <div class=\"ngg-gallery-thumbnail\">\n            <a href=\"http:\/\/www.morganacosplay.com\/wp-content\/gallery\/fran-cosplay\/DSC_5557BUENA.jpg\"\n               title=\"\"\n               data-src=\"http:\/\/www.morganacosplay.com\/wp-content\/gallery\/fran-cosplay\/DSC_5557BUENA.jpg\"\n               data-thumbnail=\"http:\/\/www.morganacosplay.com\/wp-content\/gallery\/fran-cosplay\/thumbs\/thumbs_DSC_5557BUENA.jpg\"\n               data-image-id=\"583\"\n               data-title=\"DSC_5557BUENA\"\n               data-description=\"\"\n               data-image-slug=\"dsc_5557buena\"\n               class=\"ngg-fancybox\" rel=\"db74aff99c24009bc42d803e47d53a77\">\n                <img\n                    title=\"DSC_5557BUENA\"\n                    alt=\"DSC_5557BUENA\"\n                    src=\"http:\/\/www.morganacosplay.com\/wp-content\/gallery\/fran-cosplay\/thumbs\/thumbs_DSC_5557BUENA.jpg\"\n                    width=\"230\"\n                    height=\"180\"\n                    style=\"max-width:100%;\"\n                \/>\n            <\/a>\n        <\/div>\n\t\t\t\t\t\t\t<\/div> \n\t\t\t\n                            \n\t\t\t\t<div id=\"ngg-image-1\" class=\"ngg-gallery-thumbnail-box\" >\n\t\t\t\t        <div class=\"ngg-gallery-thumbnail\">\n            <a href=\"http:\/\/www.morganacosplay.com\/wp-content\/gallery\/fran-cosplay\/DSC_5525.jpg\"\n               title=\"\"\n               data-src=\"http:\/\/www.morganacosplay.com\/wp-content\/gallery\/fran-cosplay\/DSC_5525.jpg\"\n               data-thumbnail=\"http:\/\/www.morganacosplay.com\/wp-content\/gallery\/fran-cosplay\/thumbs\/thumbs_DSC_5525.jpg\"\n               data-image-id=\"603\"\n               data-title=\"DSC_5525\"\n               data-description=\"\"\n               data-image-slug=\"dsc_5525\"\n               class=\"ngg-fancybox\" rel=\"db74aff99c24009bc42d803e47d53a77\">\n                <img\n                    title=\"DSC_5525\"\n                    alt=\"DSC_5525\"\n                    src=\"http:\/\/www.morganacosplay.com\/wp-content\/gallery\/fran-cosplay\/thumbs\/thumbs_DSC_5525.jpg\"\n                    width=\"230\"\n                    height=\"180\"\n                    style=\"max-width:100%;\"\n                \/>\n            <\/a>\n        <\/div>\n\t\t\t\t\t\t\t<\/div> \n\t\t\t\n                            \n\t\t\t\t<div id=\"ngg-image-2\" class=\"ngg-gallery-thumbnail-box\" >\n\t\t\t\t        <div class=\"ngg-gallery-thumbnail\">\n            <a href=\"http:\/\/www.morganacosplay.com\/wp-content\/gallery\/fran-cosplay\/IMGP6193nfinp.jpg\"\n               title=\"\"\n               data-src=\"http:\/\/www.morganacosplay.com\/wp-content\/gallery\/fran-cosplay\/IMGP6193nfinp.jpg\"\n               data-thumbnail=\"http:\/\/www.morganacosplay.com\/wp-content\/gallery\/fran-cosplay\/thumbs\/thumbs_IMGP6193nfinp.jpg\"\n               data-image-id=\"607\"\n               data-title=\"IMGP6193nfinp\"\n               data-description=\"\"\n               data-image-slug=\"imgp6193nfinp\"\n               class=\"ngg-fancybox\" rel=\"db74aff99c24009bc42d803e47d53a77\">\n                <img\n                    title=\"IMGP6193nfinp\"\n                    alt=\"IMGP6193nfinp\"\n                    src=\"http:\/\/www.morganacosplay.com\/wp-content\/gallery\/fran-cosplay\/thumbs\/thumbs_IMGP6193nfinp.jpg\"\n                    width=\"230\"\n                    height=\"180\"\n                    style=\"max-width:100%;\"\n                \/>\n            <\/a>\n        <\/div>\n\t\t\t\t\t\t\t<\/div> \n\t\t\t\n                            \n\t\t\t\t<div id=\"ngg-image-3\" class=\"ngg-gallery-thumbnail-box\" >\n\t\t\t\t        <div class=\"ngg-gallery-thumbnail\">\n            <a href=\"http:\/\/www.morganacosplay.com\/wp-content\/gallery\/fran-cosplay\/DSC_5513.jpg\"\n               title=\"\"\n               data-src=\"http:\/\/www.morganacosplay.com\/wp-content\/gallery\/fran-cosplay\/DSC_5513.jpg\"\n               data-thumbnail=\"http:\/\/www.morganacosplay.com\/wp-content\/gallery\/fran-cosplay\/thumbs\/thumbs_DSC_5513.jpg\"\n               data-image-id=\"667\"\n               data-title=\"DSC_5513\"\n               data-description=\"\"\n               data-image-slug=\"dsc_5513\"\n               class=\"ngg-fancybox\" rel=\"db74aff99c24009bc42d803e47d53a77\">\n                <img\n                    title=\"DSC_5513\"\n                    alt=\"DSC_5513\"\n                    src=\"http:\/\/www.morganacosplay.com\/wp-content\/gallery\/fran-cosplay\/thumbs\/thumbs_DSC_5513.jpg\"\n                    width=\"230\"\n                    height=\"180\"\n                    style=\"max-width:100%;\"\n                \/>\n            <\/a>\n        <\/div>\n\t\t\t\t\t\t\t<\/div> \n\t\t\t\n                            \n\t\t\t\t<div id=\"ngg-image-4\" class=\"ngg-gallery-thumbnail-box\" >\n\t\t\t\t        <div class=\"ngg-gallery-thumbnail\">\n            <a href=\"http:\/\/www.morganacosplay.com\/wp-content\/gallery\/fran-cosplay\/DSC_5483.jpg\"\n               title=\"\"\n               data-src=\"http:\/\/www.morganacosplay.com\/wp-content\/gallery\/fran-cosplay\/DSC_5483.jpg\"\n               data-thumbnail=\"http:\/\/www.morganacosplay.com\/wp-content\/gallery\/fran-cosplay\/thumbs\/thumbs_DSC_5483.jpg\"\n               data-image-id=\"675\"\n               data-title=\"DSC_5483\"\n               data-description=\"\"\n               data-image-slug=\"dsc_5483\"\n               class=\"ngg-fancybox\" rel=\"db74aff99c24009bc42d803e47d53a77\">\n                <img\n                    title=\"DSC_5483\"\n                    alt=\"DSC_5483\"\n                    src=\"http:\/\/www.morganacosplay.com\/wp-content\/gallery\/fran-cosplay\/thumbs\/thumbs_DSC_5483.jpg\"\n                    width=\"230\"\n                    height=\"180\"\n                    style=\"max-width:100%;\"\n                \/>\n            <\/a>\n        <\/div>\n\t\t\t\t\t\t\t<\/div> \n\t\t\t\n                            \n\t\t\t\t<div id=\"ngg-image-5\" class=\"ngg-gallery-thumbnail-box\" >\n\t\t\t\t        <div class=\"ngg-gallery-thumbnail\">\n            <a href=\"http:\/\/www.morganacosplay.com\/wp-content\/gallery\/fran-cosplay\/DSC_5589.jpg\"\n               title=\"\"\n               data-src=\"http:\/\/www.morganacosplay.com\/wp-content\/gallery\/fran-cosplay\/DSC_5589.jpg\"\n               data-thumbnail=\"http:\/\/www.morganacosplay.com\/wp-content\/gallery\/fran-cosplay\/thumbs\/thumbs_DSC_5589.jpg\"\n               data-image-id=\"677\"\n               data-title=\"DSC_5589\"\n               data-description=\"\"\n               data-image-slug=\"dsc_5589\"\n               class=\"ngg-fancybox\" rel=\"db74aff99c24009bc42d803e47d53a77\">\n                <img\n                    title=\"DSC_5589\"\n                    alt=\"DSC_5589\"\n                    src=\"http:\/\/www.morganacosplay.com\/wp-content\/gallery\/fran-cosplay\/thumbs\/thumbs_DSC_5589.jpg\"\n                    width=\"230\"\n                    height=\"180\"\n                    style=\"max-width:100%;\"\n                \/>\n            <\/a>\n        <\/div>\n\t\t\t\t\t\t\t<\/div> \n\t\t\t\n                            \n\t\t\t\t<div id=\"ngg-image-6\" class=\"ngg-gallery-thumbnail-box\" >\n\t\t\t\t        <div class=\"ngg-gallery-thumbnail\">\n            <a href=\"http:\/\/www.morganacosplay.com\/wp-content\/gallery\/fran-cosplay\/DSC_5501_2.jpg\"\n               title=\"\"\n               data-src=\"http:\/\/www.morganacosplay.com\/wp-content\/gallery\/fran-cosplay\/DSC_5501_2.jpg\"\n               data-thumbnail=\"http:\/\/www.morganacosplay.com\/wp-content\/gallery\/fran-cosplay\/thumbs\/thumbs_DSC_5501_2.jpg\"\n               data-image-id=\"686\"\n               data-title=\"DSC_5501_2\"\n               data-description=\"\"\n               data-image-slug=\"dsc_5501_2\"\n               class=\"ngg-fancybox\" rel=\"db74aff99c24009bc42d803e47d53a77\">\n                <img\n                    title=\"DSC_5501_2\"\n                    alt=\"DSC_5501_2\"\n                    src=\"http:\/\/www.morganacosplay.com\/wp-content\/gallery\/fran-cosplay\/thumbs\/thumbs_DSC_5501_2.jpg\"\n                    width=\"230\"\n                    height=\"180\"\n                    style=\"max-width:100%;\"\n                \/>\n            <\/a>\n        <\/div>\n\t\t\t\t\t\t\t<\/div> \n\t\t\t\n                            \n\t\t\t\t<div id=\"ngg-image-7\" class=\"ngg-gallery-thumbnail-box\" >\n\t\t\t\t        <div class=\"ngg-gallery-thumbnail\">\n            <a href=\"http:\/\/www.morganacosplay.com\/wp-content\/gallery\/fran-cosplay\/DSC_5545.jpg\"\n               title=\"\"\n               data-src=\"http:\/\/www.morganacosplay.com\/wp-content\/gallery\/fran-cosplay\/DSC_5545.jpg\"\n               data-thumbnail=\"http:\/\/www.morganacosplay.com\/wp-content\/gallery\/fran-cosplay\/thumbs\/thumbs_DSC_5545.jpg\"\n               data-image-id=\"697\"\n               data-title=\"DSC_5545\"\n               data-description=\"\"\n               data-image-slug=\"dsc_5545\"\n               class=\"ngg-fancybox\" rel=\"db74aff99c24009bc42d803e47d53a77\">\n                <img\n                    title=\"DSC_5545\"\n                    alt=\"DSC_5545\"\n                    src=\"http:\/\/www.morganacosplay.com\/wp-content\/gallery\/fran-cosplay\/thumbs\/thumbs_DSC_5545.jpg\"\n                    width=\"230\"\n                    height=\"180\"\n                    style=\"max-width:100%;\"\n                \/>\n            <\/a>\n        <\/div>\n\t\t\t\t\t\t\t<\/div> \n\t\t\t\n                            \n\t\t\t\t<div id=\"ngg-image-8\" class=\"ngg-gallery-thumbnail-box\" >\n\t\t\t\t        <div class=\"ngg-gallery-thumbnail\">\n            <a href=\"http:\/\/www.morganacosplay.com\/wp-content\/gallery\/fran-cosplay\/DSC_5503.jpg\"\n               title=\"\"\n               data-src=\"http:\/\/www.morganacosplay.com\/wp-content\/gallery\/fran-cosplay\/DSC_5503.jpg\"\n               data-thumbnail=\"http:\/\/www.morganacosplay.com\/wp-content\/gallery\/fran-cosplay\/thumbs\/thumbs_DSC_5503.jpg\"\n               data-image-id=\"708\"\n               data-title=\"DSC_5503\"\n               data-description=\"\"\n               data-image-slug=\"dsc_5503\"\n               class=\"ngg-fancybox\" rel=\"db74aff99c24009bc42d803e47d53a77\">\n                <img\n                    title=\"DSC_5503\"\n                    alt=\"DSC_5503\"\n                    src=\"http:\/\/www.morganacosplay.com\/wp-content\/gallery\/fran-cosplay\/thumbs\/thumbs_DSC_5503.jpg\"\n                    width=\"230\"\n                    height=\"180\"\n                    style=\"max-width:100%;\"\n                \/>\n            <\/a>\n        <\/div>\n\t\t\t\t\t\t\t<\/div> \n\t\t\t\n                            \n\t\t\t\t<div id=\"ngg-image-9\" class=\"ngg-gallery-thumbnail-box\" >\n\t\t\t\t        <div class=\"ngg-gallery-thumbnail\">\n            <a href=\"http:\/\/www.morganacosplay.com\/wp-content\/gallery\/fran-cosplay\/FranPeque.jpg\"\n               title=\"\"\n               data-src=\"http:\/\/www.morganacosplay.com\/wp-content\/gallery\/fran-cosplay\/FranPeque.jpg\"\n               data-thumbnail=\"http:\/\/www.morganacosplay.com\/wp-content\/gallery\/fran-cosplay\/thumbs\/thumbs_FranPeque.jpg\"\n               data-image-id=\"914\"\n               data-title=\"FranPeque\"\n               data-description=\"\"\n               data-image-slug=\"franpeque\"\n               class=\"ngg-fancybox\" rel=\"db74aff99c24009bc42d803e47d53a77\">\n                <img\n                    title=\"FranPeque\"\n                    alt=\"FranPeque\"\n                    src=\"http:\/\/www.morganacosplay.com\/wp-content\/gallery\/fran-cosplay\/thumbs\/thumbs_FranPeque.jpg\"\n                    width=\"230\"\n                    height=\"180\"\n                    style=\"max-width:100%;\"\n                \/>\n            <\/a>\n        <\/div>\n\t\t\t\t\t\t\t<\/div> \n\t\t\t\n                            \n\t\t\n\t\t<!-- Pagination -->\n\t<div class='ngg-clear'><\/div>\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Llevo queri\u00e9ndome hacer a Fran desde que s\u00e9 lo que es el cosplay. Fue un flechazo. As\u00ed que despu\u00e9s de tantos a\u00f1os, por fin he podido realizar uno de mis cosplays so\u00f1ados, espero que os guste el resultado!!<\/p>\n<p>[ngg_images source=\u00bbgalleries\u00bb container_id&#8230;<\/p>\n","protected":false},"author":1,"featured_media":2778,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"jetpack_post_was_ever_published":false,"jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[10],"tags":[],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.7.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Fran Cosplay - Morgana Cosplay<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.morganacosplay.com\/es_ES\/portfolio\/fran-cosplay\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fran Cosplay - Morgana Cosplay\" \/>\n<meta property=\"og:description\" content=\"Llevo queri\u00e9ndome hacer a Fran desde que s\u00e9 lo que es el cosplay. Fue un flechazo. As\u00ed que despu\u00e9s de tantos a\u00f1os, por fin he podido realizar uno de mis cosplays so\u00f1ados, espero que os guste el resultado!! [ngg_images source=&quot;galleries&quot; container_id...\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.morganacosplay.com\/es_ES\/portfolio\/fran-cosplay\/\" \/>\n<meta property=\"og:site_name\" content=\"Morgana Cosplay\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/MorganaCosplaySpain\" \/>\n<meta property=\"article:published_time\" content=\"2016-09-08T19:41:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-08-01T15:05:56+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.morganacosplay.com\/wp-content\/uploads\/2016\/09\/CabeceraWeb.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"316\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Morgana\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@MorganaCosplay\" \/>\n<meta name=\"twitter:site\" content=\"@MorganaCosplay\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Morgana\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\/\/www.morganacosplay.com\/es_ES\/portfolio\/fran-cosplay\/#article\",\"isPartOf\":{\"@id\":\"http:\/\/www.morganacosplay.com\/es_ES\/portfolio\/fran-cosplay\/\"},\"author\":{\"name\":\"Morgana\",\"@id\":\"http:\/\/www.morganacosplay.com\/en_US\/#\/schema\/person\/e038c21f6383e218990af0d2eee1bbb6\"},\"headline\":\"Fran Cosplay\",\"datePublished\":\"2016-09-08T19:41:35+00:00\",\"dateModified\":\"2017-08-01T15:05:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\/\/www.morganacosplay.com\/es_ES\/portfolio\/fran-cosplay\/\"},\"wordCount\":100,\"commentCount\":0,\"publisher\":{\"@id\":\"http:\/\/www.morganacosplay.com\/en_US\/#organization\"},\"articleSection\":[\"Portfolio\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\/\/www.morganacosplay.com\/es_ES\/portfolio\/fran-cosplay\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/www.morganacosplay.com\/es_ES\/portfolio\/fran-cosplay\/\",\"url\":\"http:\/\/www.morganacosplay.com\/es_ES\/portfolio\/fran-cosplay\/\",\"name\":\"Fran Cosplay - Morgana Cosplay\",\"isPartOf\":{\"@id\":\"http:\/\/www.morganacosplay.com\/en_US\/#website\"},\"datePublished\":\"2016-09-08T19:41:35+00:00\",\"dateModified\":\"2017-08-01T15:05:56+00:00\",\"breadcrumb\":{\"@id\":\"http:\/\/www.morganacosplay.com\/es_ES\/portfolio\/fran-cosplay\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/www.morganacosplay.com\/es_ES\/portfolio\/fran-cosplay\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/www.morganacosplay.com\/es_ES\/portfolio\/fran-cosplay\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"http:\/\/www.morganacosplay.com\/en_US\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fran Cosplay\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\/\/www.morganacosplay.com\/en_US\/#website\",\"url\":\"http:\/\/www.morganacosplay.com\/en_US\/\",\"name\":\"Morgana Cosplay\",\"description\":\"Professional Cosplayer\",\"publisher\":{\"@id\":\"http:\/\/www.morganacosplay.com\/en_US\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/www.morganacosplay.com\/en_US\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"http:\/\/www.morganacosplay.com\/en_US\/#organization\",\"name\":\"Morgana Cosplay\",\"url\":\"http:\/\/www.morganacosplay.com\/en_US\/\",\"sameAs\":[\"https:\/\/www.instagram.com\/morganacosplay\/\",\"http:\/\/youtube.com\/morganacosplay\",\"http:\/\/facebook.com\/MorganaCosplaySpain\",\"https:\/\/twitter.com\/MorganaCosplay\"],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"http:\/\/www.morganacosplay.com\/en_US\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/www.morganacosplay.com\/wp-content\/uploads\/2016\/08\/MorganaCosplayNoFondo-1.png\",\"contentUrl\":\"http:\/\/www.morganacosplay.com\/wp-content\/uploads\/2016\/08\/MorganaCosplayNoFondo-1.png\",\"width\":350,\"height\":99,\"caption\":\"Morgana Cosplay\"},\"image\":{\"@id\":\"http:\/\/www.morganacosplay.com\/en_US\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"http:\/\/www.morganacosplay.com\/en_US\/#\/schema\/person\/e038c21f6383e218990af0d2eee1bbb6\",\"name\":\"Morgana\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"http:\/\/www.morganacosplay.com\/en_US\/#\/schema\/person\/image\/\",\"url\":\"http:\/\/0.gravatar.com\/avatar\/0f17c6a9d55e6db3a6b223aaef473659?s=96&d=wavatar&r=g\",\"contentUrl\":\"http:\/\/0.gravatar.com\/avatar\/0f17c6a9d55e6db3a6b223aaef473659?s=96&d=wavatar&r=g\",\"caption\":\"Morgana\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fran Cosplay - Morgana Cosplay","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.morganacosplay.com\/es_ES\/portfolio\/fran-cosplay\/","og_locale":"es_ES","og_type":"article","og_title":"Fran Cosplay - Morgana Cosplay","og_description":"Llevo queri\u00e9ndome hacer a Fran desde que s\u00e9 lo que es el cosplay. Fue un flechazo. As\u00ed que despu\u00e9s de tantos a\u00f1os, por fin he podido realizar uno de mis cosplays so\u00f1ados, espero que os guste el resultado!! [ngg_images source=\"galleries\" container_id...","og_url":"http:\/\/www.morganacosplay.com\/es_ES\/portfolio\/fran-cosplay\/","og_site_name":"Morgana Cosplay","article_publisher":"http:\/\/facebook.com\/MorganaCosplaySpain","article_published_time":"2016-09-08T19:41:35+00:00","article_modified_time":"2017-08-01T15:05:56+00:00","og_image":[{"width":300,"height":316,"url":"http:\/\/www.morganacosplay.com\/wp-content\/uploads\/2016\/09\/CabeceraWeb.jpg","type":"image\/jpeg"}],"author":"Morgana","twitter_card":"summary_large_image","twitter_creator":"@MorganaCosplay","twitter_site":"@MorganaCosplay","twitter_misc":{"Escrito por":"Morgana"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/www.morganacosplay.com\/es_ES\/portfolio\/fran-cosplay\/#article","isPartOf":{"@id":"http:\/\/www.morganacosplay.com\/es_ES\/portfolio\/fran-cosplay\/"},"author":{"name":"Morgana","@id":"http:\/\/www.morganacosplay.com\/en_US\/#\/schema\/person\/e038c21f6383e218990af0d2eee1bbb6"},"headline":"Fran Cosplay","datePublished":"2016-09-08T19:41:35+00:00","dateModified":"2017-08-01T15:05:56+00:00","mainEntityOfPage":{"@id":"http:\/\/www.morganacosplay.com\/es_ES\/portfolio\/fran-cosplay\/"},"wordCount":100,"commentCount":0,"publisher":{"@id":"http:\/\/www.morganacosplay.com\/en_US\/#organization"},"articleSection":["Portfolio"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/www.morganacosplay.com\/es_ES\/portfolio\/fran-cosplay\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/www.morganacosplay.com\/es_ES\/portfolio\/fran-cosplay\/","url":"http:\/\/www.morganacosplay.com\/es_ES\/portfolio\/fran-cosplay\/","name":"Fran Cosplay - Morgana Cosplay","isPartOf":{"@id":"http:\/\/www.morganacosplay.com\/en_US\/#website"},"datePublished":"2016-09-08T19:41:35+00:00","dateModified":"2017-08-01T15:05:56+00:00","breadcrumb":{"@id":"http:\/\/www.morganacosplay.com\/es_ES\/portfolio\/fran-cosplay\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.morganacosplay.com\/es_ES\/portfolio\/fran-cosplay\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/www.morganacosplay.com\/es_ES\/portfolio\/fran-cosplay\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"http:\/\/www.morganacosplay.com\/en_US\/"},{"@type":"ListItem","position":2,"name":"Fran Cosplay"}]},{"@type":"WebSite","@id":"http:\/\/www.morganacosplay.com\/en_US\/#website","url":"http:\/\/www.morganacosplay.com\/en_US\/","name":"Morgana Cosplay","description":"Professional Cosplayer","publisher":{"@id":"http:\/\/www.morganacosplay.com\/en_US\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/www.morganacosplay.com\/en_US\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"http:\/\/www.morganacosplay.com\/en_US\/#organization","name":"Morgana Cosplay","url":"http:\/\/www.morganacosplay.com\/en_US\/","sameAs":["https:\/\/www.instagram.com\/morganacosplay\/","http:\/\/youtube.com\/morganacosplay","http:\/\/facebook.com\/MorganaCosplaySpain","https:\/\/twitter.com\/MorganaCosplay"],"logo":{"@type":"ImageObject","inLanguage":"es","@id":"http:\/\/www.morganacosplay.com\/en_US\/#\/schema\/logo\/image\/","url":"http:\/\/www.morganacosplay.com\/wp-content\/uploads\/2016\/08\/MorganaCosplayNoFondo-1.png","contentUrl":"http:\/\/www.morganacosplay.com\/wp-content\/uploads\/2016\/08\/MorganaCosplayNoFondo-1.png","width":350,"height":99,"caption":"Morgana Cosplay"},"image":{"@id":"http:\/\/www.morganacosplay.com\/en_US\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"http:\/\/www.morganacosplay.com\/en_US\/#\/schema\/person\/e038c21f6383e218990af0d2eee1bbb6","name":"Morgana","image":{"@type":"ImageObject","inLanguage":"es","@id":"http:\/\/www.morganacosplay.com\/en_US\/#\/schema\/person\/image\/","url":"http:\/\/0.gravatar.com\/avatar\/0f17c6a9d55e6db3a6b223aaef473659?s=96&d=wavatar&r=g","contentUrl":"http:\/\/0.gravatar.com\/avatar\/0f17c6a9d55e6db3a6b223aaef473659?s=96&d=wavatar&r=g","caption":"Morgana"}}]}},"jetpack_featured_media_url":"http:\/\/www.morganacosplay.com\/wp-content\/uploads\/2016\/09\/CabeceraWeb.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p4BLbe-II","_links":{"self":[{"href":"http:\/\/www.morganacosplay.com\/es_ES\/wp-json\/wp\/v2\/posts\/2772"}],"collection":[{"href":"http:\/\/www.morganacosplay.com\/es_ES\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.morganacosplay.com\/es_ES\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.morganacosplay.com\/es_ES\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.morganacosplay.com\/es_ES\/wp-json\/wp\/v2\/comments?post=2772"}],"version-history":[{"count":4,"href":"http:\/\/www.morganacosplay.com\/es_ES\/wp-json\/wp\/v2\/posts\/2772\/revisions"}],"predecessor-version":[{"id":3499,"href":"http:\/\/www.morganacosplay.com\/es_ES\/wp-json\/wp\/v2\/posts\/2772\/revisions\/3499"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.morganacosplay.com\/es_ES\/wp-json\/wp\/v2\/media\/2778"}],"wp:attachment":[{"href":"http:\/\/www.morganacosplay.com\/es_ES\/wp-json\/wp\/v2\/media?parent=2772"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.morganacosplay.com\/es_ES\/wp-json\/wp\/v2\/categories?post=2772"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.morganacosplay.com\/es_ES\/wp-json\/wp\/v2\/tags?post=2772"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}